{"id":888,"date":"2020-07-17T20:34:14","date_gmt":"2020-07-17T20:34:14","guid":{"rendered":"https:\/\/tradex.mx\/e-tradex\/expo-manualidades\/?page_id=888"},"modified":"2020-07-17T20:34:14","modified_gmt":"2020-07-17T20:34:14","slug":"contacto","status":"publish","type":"page","link":"https:\/\/www.expomanualidades.info\/negocios-247\/contacto\/","title":{"rendered":"Contacto"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column]\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f6-o1\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"6\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/negocios-247\/wp-json\/wp\/v2\/pages\/888#wpcf7-f6-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"6\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.4\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f6-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<div class=\"vc_col-sm-6\">\n\t<p> Nombre Completo<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"nombre\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"nombre\" \/><\/span>\n\t<\/p>\n\t<p> Tel\u00e9fono<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"telefono\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"telefono\" \/><\/span>\n\t<\/p>\n\t<p> Correo Electr\u00f3nico<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span>\n\t<\/p>\n<\/div>\n<div class=\"vc_col-sm-6\">\n\t<p> Comentarios<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"comentarios\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" name=\"comentarios\"><\/textarea><\/span>\n\t<\/p>\n<\/div>\n<p style=\"clear:both;\">&nbsp;\n<\/p>\n\n<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Enviar\" \/>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n[\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][\/vc_column][\/vc_row]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"templates\/full-width.php","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"class_list":["post-888","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.expomanualidades.info\/negocios-247\/wp-json\/wp\/v2\/pages\/888","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.expomanualidades.info\/negocios-247\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.expomanualidades.info\/negocios-247\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.expomanualidades.info\/negocios-247\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.expomanualidades.info\/negocios-247\/wp-json\/wp\/v2\/comments?post=888"}],"version-history":[{"count":1,"href":"https:\/\/www.expomanualidades.info\/negocios-247\/wp-json\/wp\/v2\/pages\/888\/revisions"}],"predecessor-version":[{"id":889,"href":"https:\/\/www.expomanualidades.info\/negocios-247\/wp-json\/wp\/v2\/pages\/888\/revisions\/889"}],"wp:attachment":[{"href":"https:\/\/www.expomanualidades.info\/negocios-247\/wp-json\/wp\/v2\/media?parent=888"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}