{"id":2337,"date":"2020-10-01T16:19:09","date_gmt":"2020-10-01T16:19:09","guid":{"rendered":"https:\/\/tradex.mx\/e-tradex\/expo-manualidades\/?page_id=2337"},"modified":"2020-10-16T16:41:41","modified_gmt":"2020-10-16T16:41:41","slug":"jabones-y-velas","status":"publish","type":"page","link":"https:\/\/www.expomanualidades.info\/negocios-247\/jabones-y-velas\/","title":{"rendered":"Jabones y velas"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text css=&#8221;.vc_custom_1602865841192{margin-top: -30px !important;}&#8221;]<!-- directorist-shortcode:: [ directorist_all_listing] -->\n<div class=\"directorist-archive-contents directorist-contents-wrap directorist-w-100 directorist-instant-search\"data-atts=\"{&quot;category&quot;:&quot;jabones-velas&quot;,&quot;_current_page&quot;:&quot;listing&quot;,&quot;category_custom_fields_relations&quot;:{&quot;128&quot;:6,&quot;81&quot;:5,&quot;77&quot;:6}}\">\n    <div class=\"directorist-archive-contents__top\">\n        \n        \n<div class=\"directorist-header-bar\">\n    <div class=\"directorist-container-fluid\">\n        <div class=\"directorist-listings-header\">\n\n            \n                <div class=\"directorist-listings-header__left\">\n\n                    \n                    <span class='directorist-header-found-title'><span>6<\/span> Resultados encontrados<\/span>                <\/div>\n\n            \n            \n                <div class=\"directorist-listings-header__right\">\n                    \n<div class=\"directorist-viewas\">\n    <!-- Archive sidebar offcanvas toggle -->\n        \n        <a class=\"directorist-viewas__item directorist-viewas__item--grid active\" href=\"\/negocios-247\/wp-json\/wp\/v2\/pages\/2337?view=grid\" aria-label=\"grid view\">\n                            <i class=\"directorist-icon-mask\" aria-hidden=\"true\" style=\"--directorist-icon: url(https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/plugins\/directorist\/assets\/icons\/font-awesome\/svgs\/solid\/grip-horizontal.svg)\"><\/i>                    <\/a>\n    \n        <a class=\"directorist-viewas__item directorist-viewas__item--list \" href=\"\/negocios-247\/wp-json\/wp\/v2\/pages\/2337?view=list\" aria-label=\"list view\">\n                            <i class=\"directorist-icon-mask\" aria-hidden=\"true\" style=\"--directorist-icon: url(https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/plugins\/directorist\/assets\/icons\/font-awesome\/svgs\/solid\/list.svg)\"><\/i>                    <\/a>\n    <\/div>\n<div class=\"directorist-dropdown directorist-dropdown-js directorist-sortby-dropdown\">\n\n    <button class=\"directorist-dropdown__toggle directorist-dropdown__toggle-js directorist-btn directorist-btn-sm directorist-toggle-has-icon\">Ordenar por<span class=\"directorist-icon-caret\"><\/span><\/button>\n\n    <div class=\"directorist-dropdown__links directorist-dropdown__links-js directorist-dropdown__links__right\">\n\n        <form id=\"directorsit-listing-sort\" method=\"post\" action=\"#\">\n                            <a href=\"#\" class=\"directorist-dropdown__links__single directorist-dropdown__links__single-js \" data-link=\"\/negocios-247\/wp-json\/wp\/v2\/pages\/2337?sort=title-asc\">A to Z (title)<\/a>\n                                <a href=\"#\" class=\"directorist-dropdown__links__single directorist-dropdown__links__single-js \" data-link=\"\/negocios-247\/wp-json\/wp\/v2\/pages\/2337?sort=title-desc\">Z to A (title)<\/a>\n                                <a href=\"#\" class=\"directorist-dropdown__links__single directorist-dropdown__links__single-js \" data-link=\"\/negocios-247\/wp-json\/wp\/v2\/pages\/2337?sort=date-desc\">Latest listings<\/a>\n                                <a href=\"#\" class=\"directorist-dropdown__links__single directorist-dropdown__links__single-js \" data-link=\"\/negocios-247\/wp-json\/wp\/v2\/pages\/2337?sort=date-asc\">Oldest listings<\/a>\n                        <\/form>\n\n    <\/div>\n\n<\/div>                <\/div>\n\n            \n        <\/div>\n    <\/div>\n<\/div>\n\n<div class=\"directorist-search-modal directorist-search-modal--full\">\n    <div class=\"directorist-search-modal__overlay\"><\/div>\n    <div class=\"directorist-search-modal__contents directorist-archive-adv-filter directorist-advanced-filter\">\n        <form action=\"https:\/\/www.expomanualidades.info\/negocios-247\/resultado-de-busqueda\/\" class=\"directorist-advanced-filter__form\">\n            <div class=\"directorist-search-modal__contents__header\">\n                <h3 class=\"directorist-search-modal__contents__title\">More Filters<\/h3>\n                <button class=\"directorist-search-modal__contents__btn directorist-search-modal__contents__btn--close\">\n                    <i class=\"directorist-icon-mask\" aria-hidden=\"true\" style=\"--directorist-icon: url(https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/plugins\/directorist\/assets\/icons\/font-awesome\/svgs\/solid\/times.svg)\"><\/i>                <\/button>\n                <span class=\"directorist-search-modal__minimizer\"><\/span>\n            <\/div>\n\n            <div class=\"directorist-search-modal__contents__body\">\n                <input type=\"hidden\" name='directory_type' value='general'>\n                <div class=\"directorist-advanced-filter__basic\">\n                                            <div class=\"directorist-advanced-filter__basic__element\">\n<div class=\"directorist-search-field directorist-form-group directorist-search-query \">\n\n            <label class=\"directorist-search-field__label\" for=\"\">\u00bfQue producto o empresa buscas?<\/label>\n    \n    <input class=\"directorist-form-element directorist-search-field__input\" id=\"\" type=\"text\" name=\"q\" value=\"\" placeholder=\"\u00bfQue producto buscas?\" >\n\n    <div class=\"directorist-search-field__btn directorist-search-field__btn--clear\">\n        <i class=\"directorist-icon-mask\" aria-hidden=\"true\" style=\"--directorist-icon: url(https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/plugins\/directorist\/assets\/icons\/font-awesome\/svgs\/solid\/times-circle.svg)\"><\/i>    <\/div>\n\n<\/div><\/div>\n                                            <div class=\"directorist-advanced-filter__basic__element\"><div class=\"directorist-search-field directorist-form-group \">\n    <div class=\"directorist-select directorist-search-category directorist-search-field__input\">\n\n                    <label class=\"directorist-search-field__label\">Categoria<\/label>\n        \n        <select name=\"in_cat\" class=\"directory_field bdas-category-search directorist-category-select\" data-placeholder=\"Categoria\"  data-isSearch=\"true\" data-selected-id=\"\" data-selected-label=\"\">\n            <option value=\"\">Select Category<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"64\">Arte y pintura<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"66\">Bordado y Tejido<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"61\">Confecci\u00f3n<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"69\">Decoraci\u00f3n<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"59\">Felting<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"72\">Jabones y velas<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"49\">Joyer\u00eda<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"74\">Libros<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"47\">Madera<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"67\">Manualidades en general<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"46\">Pasta Flexible<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"51\">Patchwork y quilting<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"43\">Reposter\u00eda<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"58\">Scrapbook<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"53\">Tarjeter\u00eda\/ filigrana<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"55\">Telas y botones<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"76\">Todas las categor\u00edas<\/option>        <\/select>\n\n    <\/div>\n    <div class=\"directorist-search-field__btn directorist-search-field__btn--clear\">\n        <i class=\"directorist-icon-mask\" aria-hidden=\"true\" style=\"--directorist-icon: url(https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/plugins\/directorist\/assets\/icons\/font-awesome\/svgs\/solid\/times-circle.svg)\"><\/i> \n    <\/div>\n<\/div><\/div>\n                                    <\/div>\n\n                <div class=\"directorist-advanced-filter__advanced\">\n                                    <\/div>\n            <\/div>\n\n            <div class=\"directorist-search-modal__contents__footer\">\n                \n<div class=\"directorist-advanced-filter__action directorist-flex directorist-align-center directorist-justify-content-between flex-wrap\">\n\n            <button type=\"submit\" class=\"directorist-btn directorist-btn-sm directorist-btn-submit\">Aplicar filtros<\/button>\n    \n            <button type=\"submit\" class=\"directorist-btn-reset-js\">Borrar filtros<\/button>\n    \n<\/div>            <\/div>\n        <\/form>\n    <\/div>\n<\/div>    <\/div>\n    <div class=\"directorist-archive-contents__listings\">\n        \n<div class=\"directorist-archive-items directorist-archive-grid-view \">\n    <div class=\"directorist-container-fluid\">\n\n        \n        \n            <div class=\" directorist-row\">\n\n                        <div class=\"directorist-col-3\">\n                \n<article class=\"directorist-listing-single directorist-listing-single--bg directorist-listing-card directorist-listing-has-thumb directorist-single-line\">\n\n    <div class=\"directorist-listing-single__thumb\">\n\n        <div class='directorist-thumnail-card directorist-card-contain' style='height: 260px;background-color: white'><div class='directorist-thumnail-card-front-wrap'><div class='directorist-swiper directorist-swiper-listing' data-sw-items='1' data-sw-margin='2' data-sw-loop='true' data-sw-perslide='1' data-sw-speed='500' data-sw-autoplay='false' data-sw-responsive='{}'>\n\t\t\t\t\t<div class='swiper-wrapper'><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/asacof-ipn\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2021\/04\/ASACOF3_.jpg' alt='ASACOF3_' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/asacof-ipn\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2021\/04\/AJOFORTE_.jpg' alt='AJOFORTE_' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/asacof-ipn\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2021\/04\/contornoojos_.jpg' alt='contornoojos_' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/asacof-ipn\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2021\/04\/gel_.jpg' alt='gel_' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/asacof-ipn\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2021\/04\/GELPARAPIERNAS_.jpg' alt='GELPARAPIERNAS_' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/asacof-ipn\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2021\/04\/GLUCOSAMINA-removebg-preview_.fw_.png' alt='GLUCOSAMINA-removebg-preview_.fw' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/asacof-ipn\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2021\/04\/jabon_.jpg' alt='jabon_' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/asacof-ipn\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2021\/04\/REDUKGEL_.jpg' alt='REDUKGEL_' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/asacof-ipn\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2021\/04\/rimel_.jpg' alt='rimel_' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/asacof-ipn\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2021\/04\/shampoo_.jpg' alt='shampoo_' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/asacof-ipn\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2021\/04\/WhatsAppImage2020-10-24at13.02.40_.jpg' alt='WhatsAppImage2020-10-24at13.02.40_' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><\/div>\n\t\t\t\t\t<div class='directorist-swiper__navigation'>\n\t\t\t\t\t\t<div class='directorist-swiper__nav directorist-swiper__nav--prev directorist-swiper__nav--prev-listing'><i class=\"directorist-icon-mask\" aria-hidden=\"true\" style=\"--directorist-icon: url(https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/plugins\/directorist\/assets\/icons\/line-awesome\/svgs\/angle-left-solid.svg)\"><\/i><\/div>\n\t\t\t\t\t\t<div class='directorist-swiper__nav directorist-swiper__nav--next directorist-swiper__nav--next-listing'><i class=\"directorist-icon-mask\" aria-hidden=\"true\" style=\"--directorist-icon: url(https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/plugins\/directorist\/assets\/icons\/line-awesome\/svgs\/angle-right-solid.svg)\"><\/i><\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class='directorist-swiper__pagination directorist-swiper__pagination--listing'><\/div>\n\t\t\t\t<\/div><\/div><\/div>\n        <div class=\"directorist-thumb-top-left\"><\/div>\n        <div class=\"directorist-thumb-top-right\"><\/div>\n        <div class=\"directorist-thumb-bottom-left\"><\/div>\n        <div class=\"directorist-thumb-bottom-right\"><\/div>\n\n    <\/div>\n\n    <div class=\"directorist-listing-single__content\">\n        <section class=\"directorist-listing-single__info\">\n\n            \n            <header class=\"directorist-listing-single__info__top\">\n                \n<h2 class=\"directorist-listing-title\"><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/asacof-ipn\/\">Asacof Comercializadora<\/a><\/h2>\n\n            <\/header>\n\n            \n            <ul class=\"directorist-listing-single__info__list\">\n                \n<li class=\"directorist-listing-card-phone\">\n    <i class=\"directorist-icon-mask\" aria-hidden=\"true\" style=\"--directorist-icon: url(https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/plugins\/directorist\/assets\/icons\/line-awesome\/svgs\/phone-solid.svg)\"><\/i>    <a href=\"tel:5556312955\">5556312955<\/a>\n<\/li>\n<li class=\"directorist-listing-card-website\">\n    <i class=\"directorist-icon-mask\" aria-hidden=\"true\" style=\"--directorist-icon: url(https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/plugins\/directorist\/assets\/icons\/line-awesome\/svgs\/globe-solid.svg)\"><\/i>        <a target=\"_blank\" rel=\"noopener\" href=\"https:\/\/www.facebook.com\/pages\/category\/Health-Beauty\/ABC-Baba-de-Caracol-103474515072967\/\">\n        https:\/\/www.facebook.com\/pages\/category\/Health-Beauty\/ABC-Baba-de-Caracol-103474515072967\/    <\/a>\n<\/li>            <\/ul>\n\n            \n                            \n<p class=\"directorist-listing-single__info__excerpt\">\n    Somos una empresa 100% Mexicana de origen&hellip;<a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/asacof-ipn\/\"> M\u00e1s info<\/a><\/p>\n            \n                    <\/section>\n\n        <footer class=\"directorist-listing-single__meta\">\n            <div class=\"directorist-listing-single__meta__left\">\n<div class=\"directorist-listing-category\">\n            <a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/categoria\/jabones-velas\/?directory_type=general\">Jabones y velas<\/a>\n                    <div class=\"directorist-listing-category__popup\">\n                <span class=\"directorist-listing-category__extran-count\">+2<\/span>\n                <div class=\"directorist-listing-category__popup__content\">\n                    \n                        <a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/categoria\/manualidades-en-general\/?directory_type=general\"> Manualidades en general<\/a>\n\n                        \n                        <a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/categoria\/todas-las-categorias\/?directory_type=general\"> Todas las categor\u00edas<\/a>\n\n                                        <\/div>\n\n            <\/div>\n            <\/div>\n<\/div>\n            <div class=\"directorist-listing-single__meta__right\"><\/div>\n        <\/footer>\n    <\/div>\n\n<\/article>            <\/div>\n                        <div class=\"directorist-col-3\">\n                \n<article class=\"directorist-listing-single directorist-listing-single--bg directorist-listing-card directorist-listing-has-thumb directorist-single-line\">\n\n    <div class=\"directorist-listing-single__thumb\">\n\n        <div class='directorist-thumnail-card directorist-card-contain' style='height: 260px;background-color: white'><div class='directorist-thumnail-card-front-wrap'><div class='directorist-swiper directorist-swiper-listing' data-sw-items='1' data-sw-margin='2' data-sw-loop='true' data-sw-perslide='1' data-sw-speed='500' data-sw-autoplay='false' data-sw-responsive='{}'>\n\t\t\t\t\t<div class='swiper-wrapper'><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/candy-home-magnolia-home\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2021\/09\/CIERRE_.jpg' alt='CIERRE_' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/candy-home-magnolia-home\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2021\/09\/9e9b66bf-8401-48b5-85f9-c79ea8076077_.jpg' alt='9e9b66bf-8401-48b5-85f9-c79ea8076077_' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/candy-home-magnolia-home\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2021\/09\/31bb0db8-9e49-45ff-95fc-611594d0fc08_.jpg' alt='31bb0db8-9e49-45ff-95fc-611594d0fc08_' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/candy-home-magnolia-home\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2021\/09\/165773117_4016144905118672_4452333870590371000_n_.jpg' alt='165773117_4016144905118672_4452333870590371000_n_' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/candy-home-magnolia-home\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2021\/09\/218396198_4406819432717882_4791295129635829880_n_.jpg' alt='218396198_4406819432717882_4791295129635829880_n_' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/candy-home-magnolia-home\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2021\/09\/231617168_4406819356051223_3711173527192381340_n_.jpg' alt='231617168_4406819356051223_3711173527192381340_n_' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/candy-home-magnolia-home\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2021\/09\/232890919_4406819452717880_8511333461910937194_n_.jpg' alt='232890919_4406819452717880_8511333461910937194_n_' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/candy-home-magnolia-home\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2021\/09\/240186112_4445432655523226_8633173798366154030_n_.jpg' alt='240186112_4445432655523226_8633173798366154030_n_' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/candy-home-magnolia-home\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2021\/09\/a44e9dc8-8f1b-46ad-8517-daa41e53aeed_.jpg' alt='a44e9dc8-8f1b-46ad-8517-daa41e53aeed_' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/candy-home-magnolia-home\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2021\/09\/bbf6a055-f219-4c88-ab81-09866dcd6dcc_.jpg' alt='bbf6a055-f219-4c88-ab81-09866dcd6dcc_' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/candy-home-magnolia-home\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2021\/09\/c98e85c4-320c-41d8-b70e-4728ed242c74_.jpg' alt='c98e85c4-320c-41d8-b70e-4728ed242c74_' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><\/div>\n\t\t\t\t\t<div class='directorist-swiper__navigation'>\n\t\t\t\t\t\t<div class='directorist-swiper__nav directorist-swiper__nav--prev directorist-swiper__nav--prev-listing'><i class=\"directorist-icon-mask\" aria-hidden=\"true\" style=\"--directorist-icon: url(https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/plugins\/directorist\/assets\/icons\/line-awesome\/svgs\/angle-left-solid.svg)\"><\/i><\/div>\n\t\t\t\t\t\t<div class='directorist-swiper__nav directorist-swiper__nav--next directorist-swiper__nav--next-listing'><i class=\"directorist-icon-mask\" aria-hidden=\"true\" style=\"--directorist-icon: url(https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/plugins\/directorist\/assets\/icons\/line-awesome\/svgs\/angle-right-solid.svg)\"><\/i><\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class='directorist-swiper__pagination directorist-swiper__pagination--listing'><\/div>\n\t\t\t\t<\/div><\/div><\/div>\n        <div class=\"directorist-thumb-top-left\"><\/div>\n        <div class=\"directorist-thumb-top-right\"><\/div>\n        <div class=\"directorist-thumb-bottom-left\"><\/div>\n        <div class=\"directorist-thumb-bottom-right\"><\/div>\n\n    <\/div>\n\n    <div class=\"directorist-listing-single__content\">\n        <section class=\"directorist-listing-single__info\">\n\n            \n            <header class=\"directorist-listing-single__info__top\">\n                \n<h2 class=\"directorist-listing-title\"><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/candy-home-magnolia-home\/\">Candy Home &#038; Magnolia Home<\/a><\/h2>\n\n            <\/header>\n\n            \n            <ul class=\"directorist-listing-single__info__list\">\n                \n<li class=\"directorist-listing-card-phone\">\n    <i class=\"directorist-icon-mask\" aria-hidden=\"true\" style=\"--directorist-icon: url(https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/plugins\/directorist\/assets\/icons\/line-awesome\/svgs\/phone-solid.svg)\"><\/i>    <a href=\"tel:5570303868\">55 70303868<\/a>\n<\/li>            <\/ul>\n\n            \n                            \n<p class=\"directorist-listing-single__info__excerpt\">\n    JABONES ARTESANALES Y VELAS DE SOYA JABONES&hellip;<a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/candy-home-magnolia-home\/\"> M\u00e1s info<\/a><\/p>\n            \n                    <\/section>\n\n        <footer class=\"directorist-listing-single__meta\">\n            <div class=\"directorist-listing-single__meta__left\">\n<div class=\"directorist-listing-category\">\n            <a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/categoria\/decoracion\/?directory_type=general\">Decoraci\u00f3n<\/a>\n                    <div class=\"directorist-listing-category__popup\">\n                <span class=\"directorist-listing-category__extran-count\">+2<\/span>\n                <div class=\"directorist-listing-category__popup__content\">\n                    \n                        <a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/categoria\/jabones-velas\/?directory_type=general\"> Jabones y velas<\/a>\n\n                        \n                        <a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/categoria\/todas-las-categorias\/?directory_type=general\"> Todas las categor\u00edas<\/a>\n\n                                        <\/div>\n\n            <\/div>\n            <\/div>\n<\/div>\n            <div class=\"directorist-listing-single__meta__right\"><\/div>\n        <\/footer>\n    <\/div>\n\n<\/article>            <\/div>\n                        <div class=\"directorist-col-3\">\n                \n<article class=\"directorist-listing-single directorist-listing-single--bg directorist-listing-card directorist-listing-has-thumb directorist-single-line\">\n\n    <div class=\"directorist-listing-single__thumb\">\n\n        <div class='directorist-thumnail-card directorist-card-contain' style='height: 260px;background-color: white'><div class='directorist-thumnail-card-front-wrap'><div class='directorist-swiper directorist-swiper-listing' data-sw-items='1' data-sw-margin='2' data-sw-loop='true' data-sw-perslide='1' data-sw-speed='500' data-sw-autoplay='false' data-sw-responsive='{}'>\n\t\t\t\t\t<div class='swiper-wrapper'><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/crea-tijereando\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2024\/06\/298453971_555888956253813_5297563631386012154_n.jpeg' alt='298453971_555888956253813_5297563631386012154_n' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/crea-tijereando\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2024\/06\/Yute-calibres.jpg' alt='Yute-calibres' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/crea-tijereando\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2024\/06\/Henequen-Calibres.jpg' alt='Henequen-Calibres' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><\/div>\n\t\t\t\t\t<div class='directorist-swiper__navigation'>\n\t\t\t\t\t\t<div class='directorist-swiper__nav directorist-swiper__nav--prev directorist-swiper__nav--prev-listing'><i class=\"directorist-icon-mask\" aria-hidden=\"true\" style=\"--directorist-icon: url(https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/plugins\/directorist\/assets\/icons\/line-awesome\/svgs\/angle-left-solid.svg)\"><\/i><\/div>\n\t\t\t\t\t\t<div class='directorist-swiper__nav directorist-swiper__nav--next directorist-swiper__nav--next-listing'><i class=\"directorist-icon-mask\" aria-hidden=\"true\" style=\"--directorist-icon: url(https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/plugins\/directorist\/assets\/icons\/line-awesome\/svgs\/angle-right-solid.svg)\"><\/i><\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class='directorist-swiper__pagination directorist-swiper__pagination--listing'><\/div>\n\t\t\t\t<\/div><\/div><\/div>\n        <div class=\"directorist-thumb-top-left\"><\/div>\n        <div class=\"directorist-thumb-top-right\"><\/div>\n        <div class=\"directorist-thumb-bottom-left\"><\/div>\n        <div class=\"directorist-thumb-bottom-right\"><\/div>\n\n    <\/div>\n\n    <div class=\"directorist-listing-single__content\">\n        <section class=\"directorist-listing-single__info\">\n\n            \n            <header class=\"directorist-listing-single__info__top\">\n                \n<h2 class=\"directorist-listing-title\"><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/crea-tijereando\/\">CREA TIJEREANDO<\/a><\/h2>\n\n            <\/header>\n\n            \n            <ul class=\"directorist-listing-single__info__list\">\n                \n<li class=\"directorist-listing-card-phone\">\n    <i class=\"directorist-icon-mask\" aria-hidden=\"true\" style=\"--directorist-icon: url(https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/plugins\/directorist\/assets\/icons\/line-awesome\/svgs\/phone-solid.svg)\"><\/i>    <a href=\"tel:+525534614070\">+52 5534614070<\/a>\n<\/li>            <\/ul>\n\n            \n                            \n<p class=\"directorist-listing-single__info__excerpt\">\n    Hilos y textiles de fibras naturales y&hellip;<a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/crea-tijereando\/\"> M\u00e1s info<\/a><\/p>\n            \n                    <\/section>\n\n        <footer class=\"directorist-listing-single__meta\">\n            <div class=\"directorist-listing-single__meta__left\">\n<div class=\"directorist-listing-category\">\n            <a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/categoria\/bordado-tejido\/?directory_type=general\">Bordado y Tejido<\/a>\n                    <div class=\"directorist-listing-category__popup\">\n                <span class=\"directorist-listing-category__extran-count\">+5<\/span>\n                <div class=\"directorist-listing-category__popup__content\">\n                    \n                        <a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/categoria\/confeccion\/?directory_type=general\"> Confecci\u00f3n<\/a>\n\n                        \n                        <a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/categoria\/decoracion\/?directory_type=general\"> Decoraci\u00f3n<\/a>\n\n                        \n                        <a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/categoria\/jabones-velas\/?directory_type=general\"> Jabones y velas<\/a>\n\n                        \n                        <a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/categoria\/manualidades-en-general\/?directory_type=general\"> Manualidades en general<\/a>\n\n                        \n                        <a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/categoria\/todas-las-categorias\/?directory_type=general\"> Todas las categor\u00edas<\/a>\n\n                                        <\/div>\n\n            <\/div>\n            <\/div>\n<\/div>\n            <div class=\"directorist-listing-single__meta__right\"><\/div>\n        <\/footer>\n    <\/div>\n\n<\/article>            <\/div>\n                        <div class=\"directorist-col-3\">\n                \n<article class=\"directorist-listing-single directorist-listing-single--bg directorist-listing-card directorist-listing-has-thumb directorist-single-line\">\n\n    <div class=\"directorist-listing-single__thumb\">\n\n        <div class='directorist-thumnail-card directorist-card-contain' style='height: 260px;background-color: white'><div class='directorist-thumnail-card-front-wrap'><div class='directorist-swiper directorist-swiper-listing' data-sw-items='1' data-sw-margin='2' data-sw-loop='true' data-sw-perslide='1' data-sw-speed='500' data-sw-autoplay='false' data-sw-responsive='{}'>\n\t\t\t\t\t<div class='swiper-wrapper'><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/creaciones-alex-crealex\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2021\/04\/2021tradexmayologo_.fw_.png' alt='2021tradexmayologo_.fw' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/creaciones-alex-crealex\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2022\/04\/crealex-tradex-1_.jpg' alt='crealex-tradex-1_' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/creaciones-alex-crealex\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2022\/04\/fleximoldes-01-1_.jpg' alt='fleximoldes-01-1_' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/creaciones-alex-crealex\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2022\/04\/fleximoldes-02-1_.jpg' alt='fleximoldes-02-1_' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/creaciones-alex-crealex\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2022\/04\/fleximoldes-03-1_.jpg' alt='fleximoldes-03-1_' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/creaciones-alex-crealex\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2022\/04\/fleximoldes-04-1_.jpg' alt='fleximoldes-04-1_' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/creaciones-alex-crealex\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2022\/04\/fleximoldes-05-1_.jpg' alt='fleximoldes-05-1_' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/creaciones-alex-crealex\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2022\/04\/fleximoldes-06-1_.jpg' alt='fleximoldes-06-1_' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/creaciones-alex-crealex\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2022\/04\/fleximoldes-07-1_.jpg' alt='fleximoldes-07-1_' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/creaciones-alex-crealex\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2022\/04\/fleximoldes-08-1_.jpg' alt='fleximoldes-08-1_' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/creaciones-alex-crealex\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2022\/04\/fleximoldes-09-1_.jpg' alt='fleximoldes-09-1_' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/creaciones-alex-crealex\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2022\/04\/fleximoldes-10_-1.jpg' alt='fleximoldes-10_' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><\/div>\n\t\t\t\t\t<div class='directorist-swiper__navigation'>\n\t\t\t\t\t\t<div class='directorist-swiper__nav directorist-swiper__nav--prev directorist-swiper__nav--prev-listing'><i class=\"directorist-icon-mask\" aria-hidden=\"true\" style=\"--directorist-icon: url(https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/plugins\/directorist\/assets\/icons\/line-awesome\/svgs\/angle-left-solid.svg)\"><\/i><\/div>\n\t\t\t\t\t\t<div class='directorist-swiper__nav directorist-swiper__nav--next directorist-swiper__nav--next-listing'><i class=\"directorist-icon-mask\" aria-hidden=\"true\" style=\"--directorist-icon: url(https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/plugins\/directorist\/assets\/icons\/line-awesome\/svgs\/angle-right-solid.svg)\"><\/i><\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class='directorist-swiper__pagination directorist-swiper__pagination--listing'><\/div>\n\t\t\t\t<\/div><\/div><\/div>\n        <div class=\"directorist-thumb-top-left\"><\/div>\n        <div class=\"directorist-thumb-top-right\"><\/div>\n        <div class=\"directorist-thumb-bottom-left\"><\/div>\n        <div class=\"directorist-thumb-bottom-right\"><\/div>\n\n    <\/div>\n\n    <div class=\"directorist-listing-single__content\">\n        <section class=\"directorist-listing-single__info\">\n\n            \n            <header class=\"directorist-listing-single__info__top\">\n                \n<h2 class=\"directorist-listing-title\"><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/creaciones-alex-crealex\/\">Creaciones Alex &#8220;CREALEX&#8221;<\/a><\/h2>\n\n            <\/header>\n\n            \n            <ul class=\"directorist-listing-single__info__list\">\n                \n<li class=\"directorist-listing-card-phone\">\n    <i class=\"directorist-icon-mask\" aria-hidden=\"true\" style=\"--directorist-icon: url(https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/plugins\/directorist\/assets\/icons\/line-awesome\/svgs\/phone-solid.svg)\"><\/i>    <a href=\"tel:2225406450\">2225 40 6450<\/a>\n<\/li>\n<li class=\"directorist-listing-card-website\">\n    <i class=\"directorist-icon-mask\" aria-hidden=\"true\" style=\"--directorist-icon: url(https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/plugins\/directorist\/assets\/icons\/line-awesome\/svgs\/globe-solid.svg)\"><\/i>        <a target=\"_blank\" rel=\"noopener\" href=\"http:\/\/www.crealex.mx\/\">\n        http:\/\/www.crealex.mx\/    <\/a>\n<\/li>            <\/ul>\n\n            \n                            \n<p class=\"directorist-listing-single__info__excerpt\">\n    Fleximoldes Moldes para cualquier tipo de pastas,&hellip;<a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/creaciones-alex-crealex\/\"> M\u00e1s info<\/a><\/p>\n            \n                    <\/section>\n\n        <footer class=\"directorist-listing-single__meta\">\n            <div class=\"directorist-listing-single__meta__left\">\n<div class=\"directorist-listing-category\">\n            <a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/categoria\/decoracion\/?directory_type=general\">Decoraci\u00f3n<\/a>\n                    <div class=\"directorist-listing-category__popup\">\n                <span class=\"directorist-listing-category__extran-count\">+4<\/span>\n                <div class=\"directorist-listing-category__popup__content\">\n                    \n                        <a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/categoria\/jabones-velas\/?directory_type=general\"> Jabones y velas<\/a>\n\n                        \n                        <a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/categoria\/manualidades-en-general\/?directory_type=general\"> Manualidades en general<\/a>\n\n                        \n                        <a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/categoria\/pasta-flexible\/?directory_type=general\"> Pasta Flexible<\/a>\n\n                        \n                        <a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/categoria\/reposteria\/?directory_type=general\"> Reposter\u00eda<\/a>\n\n                                        <\/div>\n\n            <\/div>\n            <\/div>\n<\/div>\n            <div class=\"directorist-listing-single__meta__right\"><\/div>\n        <\/footer>\n    <\/div>\n\n<\/article>            <\/div>\n                        <div class=\"directorist-col-3\">\n                \n<article class=\"directorist-listing-single directorist-listing-single--bg directorist-listing-card directorist-listing-has-thumb directorist-single-line\">\n\n    <div class=\"directorist-listing-single__thumb\">\n\n        <div class='directorist-thumnail-card directorist-card-contain' style='height: 260px;background-color: white'><div class='directorist-thumnail-card-front-wrap'><div class='directorist-swiper directorist-swiper-listing' data-sw-items='1' data-sw-margin='2' data-sw-loop='true' data-sw-perslide='1' data-sw-speed='500' data-sw-autoplay='false' data-sw-responsive='{}'>\n\t\t\t\t\t<div class='swiper-wrapper'><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/ergo-cream-3\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2023\/03\/0042C70B-0A86-4821-869A-52674305D80E.png' alt='0042C70B-0A86-4821-869A-52674305D80E' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/ergo-cream-3\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2023\/03\/ergo-cream1.jpeg' alt='ergo-cream1' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/ergo-cream-3\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2023\/03\/ergo-cream2.jpeg' alt='ergo-cream2' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/ergo-cream-3\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2023\/03\/ergo-cream4.jpeg' alt='ergo-cream4' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/ergo-cream-3\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2023\/03\/ergo-cream5.jpeg' alt='ergo-cream5' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/ergo-cream-3\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2023\/03\/ergo-cream6.jpeg' alt='ergo-cream6' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/ergo-cream-3\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2023\/03\/ergo-cream7.jpeg' alt='ergo-cream7' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/ergo-cream-3\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2023\/03\/ergo-cream8.jpeg' alt='ergo-cream8' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/ergo-cream-3\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2023\/03\/ergo-cream3.jpg' alt='ergo-cream3' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><\/div>\n\t\t\t\t\t<div class='directorist-swiper__navigation'>\n\t\t\t\t\t\t<div class='directorist-swiper__nav directorist-swiper__nav--prev directorist-swiper__nav--prev-listing'><i class=\"directorist-icon-mask\" aria-hidden=\"true\" style=\"--directorist-icon: url(https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/plugins\/directorist\/assets\/icons\/line-awesome\/svgs\/angle-left-solid.svg)\"><\/i><\/div>\n\t\t\t\t\t\t<div class='directorist-swiper__nav directorist-swiper__nav--next directorist-swiper__nav--next-listing'><i class=\"directorist-icon-mask\" aria-hidden=\"true\" style=\"--directorist-icon: url(https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/plugins\/directorist\/assets\/icons\/line-awesome\/svgs\/angle-right-solid.svg)\"><\/i><\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class='directorist-swiper__pagination directorist-swiper__pagination--listing'><\/div>\n\t\t\t\t<\/div><\/div><\/div>\n        <div class=\"directorist-thumb-top-left\"><\/div>\n        <div class=\"directorist-thumb-top-right\"><\/div>\n        <div class=\"directorist-thumb-bottom-left\"><\/div>\n        <div class=\"directorist-thumb-bottom-right\"><\/div>\n\n    <\/div>\n\n    <div class=\"directorist-listing-single__content\">\n        <section class=\"directorist-listing-single__info\">\n\n            \n            <header class=\"directorist-listing-single__info__top\">\n                \n<h2 class=\"directorist-listing-title\"><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/ergo-cream-3\/\">Ergo Cream<\/a><\/h2>\n\n            <\/header>\n\n            \n            <ul class=\"directorist-listing-single__info__list\">\n                \n<li class=\"directorist-listing-card-phone\">\n    <i class=\"directorist-icon-mask\" aria-hidden=\"true\" style=\"--directorist-icon: url(https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/plugins\/directorist\/assets\/icons\/line-awesome\/svgs\/phone-solid.svg)\"><\/i>    <a href=\"tel:5561852651\">5561852651<\/a>\n<\/li>            <\/ul>\n\n            \n                            \n<p class=\"directorist-listing-single__info__excerpt\">\n    Empresa mexicana que se dedica a la&hellip;<a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/ergo-cream-3\/\"> M\u00e1s info<\/a><\/p>\n            \n                    <\/section>\n\n        <footer class=\"directorist-listing-single__meta\">\n            <div class=\"directorist-listing-single__meta__left\">\n<div class=\"directorist-listing-category\">\n            <a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/categoria\/jabones-velas\/?directory_type=general\">Jabones y velas<\/a>\n                    <div class=\"directorist-listing-category__popup\">\n                <span class=\"directorist-listing-category__extran-count\">+1<\/span>\n                <div class=\"directorist-listing-category__popup__content\">\n                    \n                        <a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/categoria\/manualidades-en-general\/?directory_type=general\"> Manualidades en general<\/a>\n\n                                        <\/div>\n\n            <\/div>\n            <\/div>\n<\/div>\n            <div class=\"directorist-listing-single__meta__right\"><\/div>\n        <\/footer>\n    <\/div>\n\n<\/article>            <\/div>\n                        <div class=\"directorist-col-3\">\n                \n<article class=\"directorist-listing-single directorist-listing-single--bg directorist-listing-card directorist-listing-has-thumb directorist-single-line\">\n\n    <div class=\"directorist-listing-single__thumb\">\n\n        <div class='directorist-thumnail-card directorist-card-contain' style='height: 260px;background-color: white'><div class='directorist-thumnail-card-front-wrap'><div class='directorist-swiper directorist-swiper-listing' data-sw-items='1' data-sw-margin='2' data-sw-loop='true' data-sw-perslide='1' data-sw-speed='500' data-sw-autoplay='false' data-sw-responsive='{}'>\n\t\t\t\t\t<div class='swiper-wrapper'><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/esart\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2024\/07\/EsArtLogo-02-scaled.jpg' alt='EsArtLogo-02' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/esart\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2024\/07\/1000609968.jpg' alt='1000609968' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/esart\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2024\/07\/1000609965.jpg' alt='1000609965' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/esart\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2024\/07\/1000609962.jpg' alt='1000609962' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/esart\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2024\/07\/1000609959.jpg' alt='1000609959' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/esart\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2024\/07\/1000609953.jpg' alt='1000609953' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/esart\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2024\/07\/1000609950.jpg' alt='1000609950' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/esart\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2024\/07\/1000609941.jpg' alt='1000609941' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/esart\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2024\/07\/1000609938.jpg' alt='1000609938' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><\/div>\n\t\t\t\t\t<div class='directorist-swiper__navigation'>\n\t\t\t\t\t\t<div class='directorist-swiper__nav directorist-swiper__nav--prev directorist-swiper__nav--prev-listing'><i class=\"directorist-icon-mask\" aria-hidden=\"true\" style=\"--directorist-icon: url(https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/plugins\/directorist\/assets\/icons\/line-awesome\/svgs\/angle-left-solid.svg)\"><\/i><\/div>\n\t\t\t\t\t\t<div class='directorist-swiper__nav directorist-swiper__nav--next directorist-swiper__nav--next-listing'><i class=\"directorist-icon-mask\" aria-hidden=\"true\" style=\"--directorist-icon: url(https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/plugins\/directorist\/assets\/icons\/line-awesome\/svgs\/angle-right-solid.svg)\"><\/i><\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class='directorist-swiper__pagination directorist-swiper__pagination--listing'><\/div>\n\t\t\t\t<\/div><\/div><\/div>\n        <div class=\"directorist-thumb-top-left\"><\/div>\n        <div class=\"directorist-thumb-top-right\"><\/div>\n        <div class=\"directorist-thumb-bottom-left\"><\/div>\n        <div class=\"directorist-thumb-bottom-right\"><\/div>\n\n    <\/div>\n\n    <div class=\"directorist-listing-single__content\">\n        <section class=\"directorist-listing-single__info\">\n\n            \n            <header class=\"directorist-listing-single__info__top\">\n                \n<h2 class=\"directorist-listing-title\"><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/esart\/\">EsArt<\/a><\/h2>\n\n            <\/header>\n\n            \n            <ul class=\"directorist-listing-single__info__list\">\n                \n<li class=\"directorist-listing-card-phone\">\n    <i class=\"directorist-icon-mask\" aria-hidden=\"true\" style=\"--directorist-icon: url(https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/plugins\/directorist\/assets\/icons\/line-awesome\/svgs\/phone-solid.svg)\"><\/i>    <a href=\"tel:3316014554\">3316014554<\/a>\n<\/li>            <\/ul>\n\n            \n                            \n<p class=\"directorist-listing-single__info__excerpt\">\n    Diferentes talleres art\u00edsticos como bordado, tejido, crochet,&hellip;<a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/esart\/\"> M\u00e1s info<\/a><\/p>\n            \n                    <\/section>\n\n        <footer class=\"directorist-listing-single__meta\">\n            <div class=\"directorist-listing-single__meta__left\">\n<div class=\"directorist-listing-category\">\n            <a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/categoria\/arte-pintura\/?directory_type=general\">Arte y pintura<\/a>\n                    <div class=\"directorist-listing-category__popup\">\n                <span class=\"directorist-listing-category__extran-count\">+4<\/span>\n                <div class=\"directorist-listing-category__popup__content\">\n                    \n                        <a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/categoria\/bordado-tejido\/?directory_type=general\"> Bordado y Tejido<\/a>\n\n                        \n                        <a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/categoria\/jabones-velas\/?directory_type=general\"> Jabones y velas<\/a>\n\n                        \n                        <a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/categoria\/manualidades-en-general\/?directory_type=general\"> Manualidades en general<\/a>\n\n                        \n                        <a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/categoria\/todas-las-categorias\/?directory_type=general\"> Todas las categor\u00edas<\/a>\n\n                                        <\/div>\n\n            <\/div>\n            <\/div>\n<\/div>\n            <div class=\"directorist-listing-single__meta__right\"><\/div>\n        <\/footer>\n    <\/div>\n\n<\/article>            <\/div>\n            \n            <\/div>\n\n            \n            \n            <\/div>\n<\/div>    <\/div>\n\n<\/div>[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text css=&#8221;.vc_custom_1602865841192{margin-top: -30px !important;}&#8221;][\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"templates\/full-width.php","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"class_list":["post-2337","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.expomanualidades.info\/negocios-247\/wp-json\/wp\/v2\/pages\/2337","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.expomanualidades.info\/negocios-247\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.expomanualidades.info\/negocios-247\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.expomanualidades.info\/negocios-247\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.expomanualidades.info\/negocios-247\/wp-json\/wp\/v2\/comments?post=2337"}],"version-history":[{"count":3,"href":"https:\/\/www.expomanualidades.info\/negocios-247\/wp-json\/wp\/v2\/pages\/2337\/revisions"}],"predecessor-version":[{"id":2374,"href":"https:\/\/www.expomanualidades.info\/negocios-247\/wp-json\/wp\/v2\/pages\/2337\/revisions\/2374"}],"wp:attachment":[{"href":"https:\/\/www.expomanualidades.info\/negocios-247\/wp-json\/wp\/v2\/media?parent=2337"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}