{"id":2287,"date":"2020-10-01T15:42:12","date_gmt":"2020-10-01T15:42:12","guid":{"rendered":"https:\/\/tradex.mx\/e-tradex\/expo-manualidades\/?page_id=2287"},"modified":"2020-10-01T15:47:06","modified_gmt":"2020-10-01T15:47:06","slug":"reposteria","status":"publish","type":"page","link":"https:\/\/www.expomanualidades.info\/negocios-247\/reposteria\/","title":{"rendered":"Reposter\u00eda"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text css=&#8221;.vc_custom_1601566587487{margin-top: -30px !important;}&#8221;]<!-- directorist-shortcode:: [ directorist_all_listing] -->\n<div class=\"directorist-archive-contents directorist-contents-wrap directorist-w-100 directorist-instant-search\"data-atts=\"{&quot;category&quot;:&quot;Reposter\\u00eda&quot;,&quot;_current_page&quot;:&quot;listing&quot;,&quot;category_custom_fields_relations&quot;:{&quot;128&quot;:6,&quot;81&quot;:5,&quot;77&quot;:6}}\">\n    <div class=\"directorist-archive-contents__top\">\n        \n        \n<div class=\"directorist-header-bar\">\n    <div class=\"directorist-container-fluid\">\n        <div class=\"directorist-listings-header\">\n\n            \n                <div class=\"directorist-listings-header__left\">\n\n                    \n                    <span class='directorist-header-found-title'><span>7<\/span> Resultados encontrados<\/span>                <\/div>\n\n            \n            \n                <div class=\"directorist-listings-header__right\">\n                    \n<div class=\"directorist-viewas\">\n    <!-- Archive sidebar offcanvas toggle -->\n        \n        <a class=\"directorist-viewas__item directorist-viewas__item--grid active\" href=\"\/negocios-247\/wp-json\/wp\/v2\/pages\/2287?view=grid\" aria-label=\"grid view\">\n                            <i class=\"directorist-icon-mask\" aria-hidden=\"true\" style=\"--directorist-icon: url(https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/plugins\/directorist\/assets\/icons\/font-awesome\/svgs\/solid\/grip-horizontal.svg)\"><\/i>                    <\/a>\n    \n        <a class=\"directorist-viewas__item directorist-viewas__item--list \" href=\"\/negocios-247\/wp-json\/wp\/v2\/pages\/2287?view=list\" aria-label=\"list view\">\n                            <i class=\"directorist-icon-mask\" aria-hidden=\"true\" style=\"--directorist-icon: url(https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/plugins\/directorist\/assets\/icons\/font-awesome\/svgs\/solid\/list.svg)\"><\/i>                    <\/a>\n    <\/div>\n<div class=\"directorist-dropdown directorist-dropdown-js directorist-sortby-dropdown\">\n\n    <button class=\"directorist-dropdown__toggle directorist-dropdown__toggle-js directorist-btn directorist-btn-sm directorist-toggle-has-icon\">Ordenar por<span class=\"directorist-icon-caret\"><\/span><\/button>\n\n    <div class=\"directorist-dropdown__links directorist-dropdown__links-js directorist-dropdown__links__right\">\n\n        <form id=\"directorsit-listing-sort\" method=\"post\" action=\"#\">\n                            <a href=\"#\" class=\"directorist-dropdown__links__single directorist-dropdown__links__single-js \" data-link=\"\/negocios-247\/wp-json\/wp\/v2\/pages\/2287?sort=title-asc\">A to Z (title)<\/a>\n                                <a href=\"#\" class=\"directorist-dropdown__links__single directorist-dropdown__links__single-js \" data-link=\"\/negocios-247\/wp-json\/wp\/v2\/pages\/2287?sort=title-desc\">Z to A (title)<\/a>\n                                <a href=\"#\" class=\"directorist-dropdown__links__single directorist-dropdown__links__single-js \" data-link=\"\/negocios-247\/wp-json\/wp\/v2\/pages\/2287?sort=date-desc\">Latest listings<\/a>\n                                <a href=\"#\" class=\"directorist-dropdown__links__single directorist-dropdown__links__single-js \" data-link=\"\/negocios-247\/wp-json\/wp\/v2\/pages\/2287?sort=date-asc\">Oldest listings<\/a>\n                        <\/form>\n\n    <\/div>\n\n<\/div>                <\/div>\n\n            \n        <\/div>\n    <\/div>\n<\/div>\n\n<div class=\"directorist-search-modal directorist-search-modal--full\">\n    <div class=\"directorist-search-modal__overlay\"><\/div>\n    <div class=\"directorist-search-modal__contents directorist-archive-adv-filter directorist-advanced-filter\">\n        <form action=\"https:\/\/www.expomanualidades.info\/negocios-247\/resultado-de-busqueda\/\" class=\"directorist-advanced-filter__form\">\n            <div class=\"directorist-search-modal__contents__header\">\n                <h3 class=\"directorist-search-modal__contents__title\">More Filters<\/h3>\n                <button class=\"directorist-search-modal__contents__btn directorist-search-modal__contents__btn--close\">\n                    <i class=\"directorist-icon-mask\" aria-hidden=\"true\" style=\"--directorist-icon: url(https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/plugins\/directorist\/assets\/icons\/font-awesome\/svgs\/solid\/times.svg)\"><\/i>                <\/button>\n                <span class=\"directorist-search-modal__minimizer\"><\/span>\n            <\/div>\n\n            <div class=\"directorist-search-modal__contents__body\">\n                <input type=\"hidden\" name='directory_type' value='general'>\n                <div class=\"directorist-advanced-filter__basic\">\n                                            <div class=\"directorist-advanced-filter__basic__element\">\n<div class=\"directorist-search-field directorist-form-group directorist-search-query \">\n\n            <label class=\"directorist-search-field__label\" for=\"\">\u00bfQue producto o empresa buscas?<\/label>\n    \n    <input class=\"directorist-form-element directorist-search-field__input\" id=\"\" type=\"text\" name=\"q\" value=\"\" placeholder=\"\u00bfQue producto buscas?\" >\n\n    <div class=\"directorist-search-field__btn directorist-search-field__btn--clear\">\n        <i class=\"directorist-icon-mask\" aria-hidden=\"true\" style=\"--directorist-icon: url(https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/plugins\/directorist\/assets\/icons\/font-awesome\/svgs\/solid\/times-circle.svg)\"><\/i>    <\/div>\n\n<\/div><\/div>\n                                            <div class=\"directorist-advanced-filter__basic__element\"><div class=\"directorist-search-field directorist-form-group \">\n    <div class=\"directorist-select directorist-search-category directorist-search-field__input\">\n\n                    <label class=\"directorist-search-field__label\">Categoria<\/label>\n        \n        <select name=\"in_cat\" class=\"directory_field bdas-category-search directorist-category-select\" data-placeholder=\"Categoria\"  data-isSearch=\"true\" data-selected-id=\"\" data-selected-label=\"\">\n            <option value=\"\">Select Category<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"64\">Arte y pintura<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"66\">Bordado y Tejido<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"61\">Confecci\u00f3n<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"69\">Decoraci\u00f3n<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"59\">Felting<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"72\">Jabones y velas<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"49\">Joyer\u00eda<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"74\">Libros<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"47\">Madera<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"67\">Manualidades en general<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"46\">Pasta Flexible<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"51\">Patchwork y quilting<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"43\">Reposter\u00eda<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"58\">Scrapbook<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"53\">Tarjeter\u00eda\/ filigrana<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"55\">Telas y botones<\/option><option data-icon=\"\" data-custom-field=\"\" value=\"76\">Todas las categor\u00edas<\/option>        <\/select>\n\n    <\/div>\n    <div class=\"directorist-search-field__btn directorist-search-field__btn--clear\">\n        <i class=\"directorist-icon-mask\" aria-hidden=\"true\" style=\"--directorist-icon: url(https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/plugins\/directorist\/assets\/icons\/font-awesome\/svgs\/solid\/times-circle.svg)\"><\/i> \n    <\/div>\n<\/div><\/div>\n                                    <\/div>\n\n                <div class=\"directorist-advanced-filter__advanced\">\n                                    <\/div>\n            <\/div>\n\n            <div class=\"directorist-search-modal__contents__footer\">\n                \n<div class=\"directorist-advanced-filter__action directorist-flex directorist-align-center directorist-justify-content-between flex-wrap\">\n\n            <button type=\"submit\" class=\"directorist-btn directorist-btn-sm directorist-btn-submit\">Aplicar filtros<\/button>\n    \n            <button type=\"submit\" class=\"directorist-btn-reset-js\">Borrar filtros<\/button>\n    \n<\/div>            <\/div>\n        <\/form>\n    <\/div>\n<\/div>    <\/div>\n    <div class=\"directorist-archive-contents__listings\">\n        \n<div class=\"directorist-archive-items directorist-archive-grid-view \">\n    <div class=\"directorist-container-fluid\">\n\n        \n        \n            <div class=\" directorist-row\">\n\n                        <div class=\"directorist-col-3\">\n                \n<article class=\"directorist-listing-single directorist-listing-single--bg directorist-listing-card directorist-listing-has-thumb directorist-single-line\">\n\n    <div class=\"directorist-listing-single__thumb\">\n\n        <div class='directorist-thumnail-card directorist-card-contain' style='height: 260px;background-color: white'><div class='directorist-thumnail-card-front-wrap'><div class='directorist-swiper directorist-swiper-listing' data-sw-items='1' data-sw-margin='2' data-sw-loop='true' data-sw-perslide='1' data-sw-speed='500' data-sw-autoplay='false' data-sw-responsive='{}'>\n\t\t\t\t\t<div class='swiper-wrapper'><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/coloidales-duche-s-a-de-c-v\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2022\/09\/logo_.jpg' alt='logo_' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/coloidales-duche-s-a-de-c-v\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2022\/09\/GELIPETS_.jpg' alt='GELIPETS_' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/coloidales-duche-s-a-de-c-v\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2022\/09\/LOGO-DUCHE-CARAMELO_.jpg' alt='LOGO-DUCHE-CARAMELO_' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/coloidales-duche-s-a-de-c-v\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2022\/09\/oloesa-naranja_.jpg' alt='oloesa-naranja_' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/coloidales-duche-s-a-de-c-v\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2022\/09\/OSEAGEL.jpg' alt='OSEAGEL' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/coloidales-duche-s-a-de-c-v\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2023\/04\/COLAGENOS.jpeg' alt='COLAGENOS' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><\/div>\n\t\t\t\t\t<div class='directorist-swiper__navigation'>\n\t\t\t\t\t\t<div class='directorist-swiper__nav directorist-swiper__nav--prev directorist-swiper__nav--prev-listing'><i class=\"directorist-icon-mask\" aria-hidden=\"true\" style=\"--directorist-icon: url(https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/plugins\/directorist\/assets\/icons\/line-awesome\/svgs\/angle-left-solid.svg)\"><\/i><\/div>\n\t\t\t\t\t\t<div class='directorist-swiper__nav directorist-swiper__nav--next directorist-swiper__nav--next-listing'><i class=\"directorist-icon-mask\" aria-hidden=\"true\" style=\"--directorist-icon: url(https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/plugins\/directorist\/assets\/icons\/line-awesome\/svgs\/angle-right-solid.svg)\"><\/i><\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class='directorist-swiper__pagination directorist-swiper__pagination--listing'><\/div>\n\t\t\t\t<\/div><\/div><\/div>\n        <div class=\"directorist-thumb-top-left\"><\/div>\n        <div class=\"directorist-thumb-top-right\"><\/div>\n        <div class=\"directorist-thumb-bottom-left\"><\/div>\n        <div class=\"directorist-thumb-bottom-right\"><\/div>\n\n    <\/div>\n\n    <div class=\"directorist-listing-single__content\">\n        <section class=\"directorist-listing-single__info\">\n\n            \n            <header class=\"directorist-listing-single__info__top\">\n                \n<h2 class=\"directorist-listing-title\"><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/coloidales-duche-s-a-de-c-v\/\">COLOIDALES DUCHE S.A. DE C.V.<\/a><\/h2>\n\n            <\/header>\n\n            \n            <ul class=\"directorist-listing-single__info__list\">\n                \n<li class=\"directorist-listing-card-phone\">\n    <i class=\"directorist-icon-mask\" aria-hidden=\"true\" style=\"--directorist-icon: url(https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/plugins\/directorist\/assets\/icons\/line-awesome\/svgs\/phone-solid.svg)\"><\/i>    <a href=\"tel:5555336444\">5555336444<\/a>\n<\/li>\n<li class=\"directorist-listing-card-website\">\n    <i class=\"directorist-icon-mask\" aria-hidden=\"true\" style=\"--directorist-icon: url(https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/plugins\/directorist\/assets\/icons\/line-awesome\/svgs\/globe-solid.svg)\"><\/i>        <a target=\"_blank\" rel=\"noopener\" href=\"http:\/\/www.duche.com\">\n        http:\/\/www.duche.com    <\/a>\n<\/li>            <\/ul>\n\n            \n                            \n<p class=\"directorist-listing-single__info__excerpt\">\n    GRENETINAS, ESENCIAS, COLORES, CONCENTRADOS COL\u00c1GENOS, PRODUCTOS PARA&hellip;<a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/coloidales-duche-s-a-de-c-v\/\"> M\u00e1s info<\/a><\/p>\n            \n                    <\/section>\n\n        <footer class=\"directorist-listing-single__meta\">\n            <div class=\"directorist-listing-single__meta__left\">\n<div class=\"directorist-listing-category\">\n            <a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/categoria\/reposteria\/?directory_type=general\">Reposter\u00eda<\/a>\n                    <div class=\"directorist-listing-category__popup\">\n                <span class=\"directorist-listing-category__extran-count\">+1<\/span>\n                <div class=\"directorist-listing-category__popup__content\">\n                    \n                        <a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/categoria\/todas-las-categorias\/?directory_type=general\"> Todas las categor\u00edas<\/a>\n\n                                        <\/div>\n\n            <\/div>\n            <\/div>\n<\/div>\n            <div class=\"directorist-listing-single__meta__right\"><\/div>\n        <\/footer>\n    <\/div>\n\n<\/article>            <\/div>\n                        <div class=\"directorist-col-3\">\n                \n<article class=\"directorist-listing-single directorist-listing-single--bg directorist-listing-card directorist-listing-has-thumb directorist-single-line\">\n\n    <div class=\"directorist-listing-single__thumb\">\n\n        <div class='directorist-thumnail-card directorist-card-contain' style='height: 260px;background-color: white'><div class='directorist-thumnail-card-front-wrap'><div class='directorist-swiper directorist-swiper-listing' data-sw-items='1' data-sw-margin='2' data-sw-loop='true' data-sw-perslide='1' data-sw-speed='500' data-sw-autoplay='false' data-sw-responsive='{}'>\n\t\t\t\t\t<div class='swiper-wrapper'><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/creaciones-alex-crealex\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2021\/04\/2021tradexmayologo_.fw_.png' alt='2021tradexmayologo_.fw' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/creaciones-alex-crealex\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2022\/04\/crealex-tradex-1_.jpg' alt='crealex-tradex-1_' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/creaciones-alex-crealex\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2022\/04\/fleximoldes-01-1_.jpg' alt='fleximoldes-01-1_' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/creaciones-alex-crealex\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2022\/04\/fleximoldes-02-1_.jpg' alt='fleximoldes-02-1_' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/creaciones-alex-crealex\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2022\/04\/fleximoldes-03-1_.jpg' alt='fleximoldes-03-1_' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/creaciones-alex-crealex\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2022\/04\/fleximoldes-04-1_.jpg' alt='fleximoldes-04-1_' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/creaciones-alex-crealex\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2022\/04\/fleximoldes-05-1_.jpg' alt='fleximoldes-05-1_' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/creaciones-alex-crealex\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2022\/04\/fleximoldes-06-1_.jpg' alt='fleximoldes-06-1_' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/creaciones-alex-crealex\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2022\/04\/fleximoldes-07-1_.jpg' alt='fleximoldes-07-1_' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/creaciones-alex-crealex\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2022\/04\/fleximoldes-08-1_.jpg' alt='fleximoldes-08-1_' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/creaciones-alex-crealex\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2022\/04\/fleximoldes-09-1_.jpg' alt='fleximoldes-09-1_' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/creaciones-alex-crealex\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2022\/04\/fleximoldes-10_-1.jpg' alt='fleximoldes-10_' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><\/div>\n\t\t\t\t\t<div class='directorist-swiper__navigation'>\n\t\t\t\t\t\t<div class='directorist-swiper__nav directorist-swiper__nav--prev directorist-swiper__nav--prev-listing'><i class=\"directorist-icon-mask\" aria-hidden=\"true\" style=\"--directorist-icon: url(https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/plugins\/directorist\/assets\/icons\/line-awesome\/svgs\/angle-left-solid.svg)\"><\/i><\/div>\n\t\t\t\t\t\t<div class='directorist-swiper__nav directorist-swiper__nav--next directorist-swiper__nav--next-listing'><i class=\"directorist-icon-mask\" aria-hidden=\"true\" style=\"--directorist-icon: url(https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/plugins\/directorist\/assets\/icons\/line-awesome\/svgs\/angle-right-solid.svg)\"><\/i><\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class='directorist-swiper__pagination directorist-swiper__pagination--listing'><\/div>\n\t\t\t\t<\/div><\/div><\/div>\n        <div class=\"directorist-thumb-top-left\"><\/div>\n        <div class=\"directorist-thumb-top-right\"><\/div>\n        <div class=\"directorist-thumb-bottom-left\"><\/div>\n        <div class=\"directorist-thumb-bottom-right\"><\/div>\n\n    <\/div>\n\n    <div class=\"directorist-listing-single__content\">\n        <section class=\"directorist-listing-single__info\">\n\n            \n            <header class=\"directorist-listing-single__info__top\">\n                \n<h2 class=\"directorist-listing-title\"><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/creaciones-alex-crealex\/\">Creaciones Alex &#8220;CREALEX&#8221;<\/a><\/h2>\n\n            <\/header>\n\n            \n            <ul class=\"directorist-listing-single__info__list\">\n                \n<li class=\"directorist-listing-card-phone\">\n    <i class=\"directorist-icon-mask\" aria-hidden=\"true\" style=\"--directorist-icon: url(https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/plugins\/directorist\/assets\/icons\/line-awesome\/svgs\/phone-solid.svg)\"><\/i>    <a href=\"tel:2225406450\">2225 40 6450<\/a>\n<\/li>\n<li class=\"directorist-listing-card-website\">\n    <i class=\"directorist-icon-mask\" aria-hidden=\"true\" style=\"--directorist-icon: url(https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/plugins\/directorist\/assets\/icons\/line-awesome\/svgs\/globe-solid.svg)\"><\/i>        <a target=\"_blank\" rel=\"noopener\" href=\"http:\/\/www.crealex.mx\/\">\n        http:\/\/www.crealex.mx\/    <\/a>\n<\/li>            <\/ul>\n\n            \n                            \n<p class=\"directorist-listing-single__info__excerpt\">\n    Fleximoldes Moldes para cualquier tipo de pastas,&hellip;<a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/creaciones-alex-crealex\/\"> M\u00e1s info<\/a><\/p>\n            \n                    <\/section>\n\n        <footer class=\"directorist-listing-single__meta\">\n            <div class=\"directorist-listing-single__meta__left\">\n<div class=\"directorist-listing-category\">\n            <a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/categoria\/decoracion\/?directory_type=general\">Decoraci\u00f3n<\/a>\n                    <div class=\"directorist-listing-category__popup\">\n                <span class=\"directorist-listing-category__extran-count\">+4<\/span>\n                <div class=\"directorist-listing-category__popup__content\">\n                    \n                        <a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/categoria\/jabones-velas\/?directory_type=general\"> Jabones y velas<\/a>\n\n                        \n                        <a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/categoria\/manualidades-en-general\/?directory_type=general\"> Manualidades en general<\/a>\n\n                        \n                        <a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/categoria\/pasta-flexible\/?directory_type=general\"> Pasta Flexible<\/a>\n\n                        \n                        <a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/categoria\/reposteria\/?directory_type=general\"> Reposter\u00eda<\/a>\n\n                                        <\/div>\n\n            <\/div>\n            <\/div>\n<\/div>\n            <div class=\"directorist-listing-single__meta__right\"><\/div>\n        <\/footer>\n    <\/div>\n\n<\/article>            <\/div>\n                        <div class=\"directorist-col-3\">\n                \n<article class=\"directorist-listing-single directorist-listing-single--bg directorist-listing-card directorist-listing-has-thumb directorist-single-line\">\n\n    <div class=\"directorist-listing-single__thumb\">\n\n        <div class='directorist-thumnail-card directorist-card-contain' style='height: 260px;background-color: white'><div class='directorist-thumnail-card-front-wrap'><div class='directorist-swiper directorist-swiper-listing' data-sw-items='1' data-sw-margin='2' data-sw-loop='true' data-sw-perslide='1' data-sw-speed='500' data-sw-autoplay='false' data-sw-responsive='{}'>\n\t\t\t\t\t<div class='swiper-wrapper'><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/delicatesses\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2021\/09\/LOGODALICATESSESpng_.fw_.png' alt='LOGODALICATESSESpng_.fw' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/delicatesses\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2021\/09\/BOMBONES_.jpg' alt='BOMBONES_' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/delicatesses\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2021\/09\/BOMBONES1_.jpg' alt='BOMBONES1_' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/delicatesses\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2021\/09\/BOMBONES2_.jpg' alt='BOMBONES2_' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/delicatesses\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2021\/09\/BOMBONES3_.jpg' alt='BOMBONES3_' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/delicatesses\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2021\/09\/BOMBONES4_.jpg' alt='BOMBONES4_' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/delicatesses\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2021\/09\/BOMBONESRELLENOS_.jpg' alt='BOMBONESRELLENOS_' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/delicatesses\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2021\/09\/TRUFAS1_.jpg' alt='TRUFAS1_' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/delicatesses\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2021\/09\/TRUFAS2_.jpg' alt='TRUFAS2_' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/delicatesses\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2021\/09\/TRUFAS3_.jpg' alt='TRUFAS3_' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><\/div>\n\t\t\t\t\t<div class='directorist-swiper__navigation'>\n\t\t\t\t\t\t<div class='directorist-swiper__nav directorist-swiper__nav--prev directorist-swiper__nav--prev-listing'><i class=\"directorist-icon-mask\" aria-hidden=\"true\" style=\"--directorist-icon: url(https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/plugins\/directorist\/assets\/icons\/line-awesome\/svgs\/angle-left-solid.svg)\"><\/i><\/div>\n\t\t\t\t\t\t<div class='directorist-swiper__nav directorist-swiper__nav--next directorist-swiper__nav--next-listing'><i class=\"directorist-icon-mask\" aria-hidden=\"true\" style=\"--directorist-icon: url(https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/plugins\/directorist\/assets\/icons\/line-awesome\/svgs\/angle-right-solid.svg)\"><\/i><\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class='directorist-swiper__pagination directorist-swiper__pagination--listing'><\/div>\n\t\t\t\t<\/div><\/div><\/div>\n        <div class=\"directorist-thumb-top-left\"><\/div>\n        <div class=\"directorist-thumb-top-right\"><\/div>\n        <div class=\"directorist-thumb-bottom-left\"><\/div>\n        <div class=\"directorist-thumb-bottom-right\"><\/div>\n\n    <\/div>\n\n    <div class=\"directorist-listing-single__content\">\n        <section class=\"directorist-listing-single__info\">\n\n            \n            <header class=\"directorist-listing-single__info__top\">\n                \n<h2 class=\"directorist-listing-title\"><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/delicatesses\/\">D\u00e9licatesses<\/a><\/h2>\n\n            <\/header>\n\n            \n            <ul class=\"directorist-listing-single__info__list\">\n                \n<li class=\"directorist-listing-card-phone\">\n    <i class=\"directorist-icon-mask\" aria-hidden=\"true\" style=\"--directorist-icon: url(https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/plugins\/directorist\/assets\/icons\/line-awesome\/svgs\/phone-solid.svg)\"><\/i>    <a href=\"tel:5573873937\">5573873937<\/a>\n<\/li>            <\/ul>\n\n            \n                            \n<p class=\"directorist-listing-single__info__excerpt\">\n    bomboner\u00eda tradicional con chocolate real de alta&hellip;<a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/delicatesses\/\"> M\u00e1s info<\/a><\/p>\n            \n                    <\/section>\n\n        <footer class=\"directorist-listing-single__meta\">\n            <div class=\"directorist-listing-single__meta__left\">\n<div class=\"directorist-listing-category\">\n            <a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/categoria\/manualidades-en-general\/?directory_type=general\">Manualidades en general<\/a>\n                    <div class=\"directorist-listing-category__popup\">\n                <span class=\"directorist-listing-category__extran-count\">+2<\/span>\n                <div class=\"directorist-listing-category__popup__content\">\n                    \n                        <a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/categoria\/reposteria\/?directory_type=general\"> Reposter\u00eda<\/a>\n\n                        \n                        <a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/categoria\/todas-las-categorias\/?directory_type=general\"> Todas las categor\u00edas<\/a>\n\n                                        <\/div>\n\n            <\/div>\n            <\/div>\n<\/div>\n            <div class=\"directorist-listing-single__meta__right\"><\/div>\n        <\/footer>\n    <\/div>\n\n<\/article>            <\/div>\n                        <div class=\"directorist-col-3\">\n                \n<article class=\"directorist-listing-single directorist-listing-single--bg directorist-listing-card directorist-listing-has-thumb directorist-single-line\">\n\n    <div class=\"directorist-listing-single__thumb\">\n\n        <div class='directorist-thumnail-card directorist-card-contain' style='height: 260px;background-color: white'><div class='directorist-thumnail-card-front-wrap'><div class='directorist-swiper directorist-swiper-listing' data-sw-items='1' data-sw-margin='2' data-sw-loop='true' data-sw-perslide='1' data-sw-speed='500' data-sw-autoplay='false' data-sw-responsive='{}'>\n\t\t\t\t\t<div class='swiper-wrapper'><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/dulate-mini-postres\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2020\/09\/dulate.fw_.png' alt='dulate.fw' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/dulate-mini-postres\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2020\/09\/4C61F09E-9AB2-4D35-A09A-167CA4A50C78-1.jpg' alt='4C61F09E-9AB2-4D35-A09A-167CA4A50C78' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/dulate-mini-postres\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2020\/09\/7F671EF4-53C1-4E35-980E-68436BDF1D31-1.jpg' alt='7F671EF4-53C1-4E35-980E-68436BDF1D31' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/dulate-mini-postres\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2020\/09\/9F9742B6-FF72-4859-A1C4-B3F019E7CD05-1.jpg' alt='9F9742B6-FF72-4859-A1C4-B3F019E7CD05' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/dulate-mini-postres\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2020\/09\/2545904B-860C-41F9-B728-E481CA93CB67-1.jpg' alt='2545904B-860C-41F9-B728-E481CA93CB67' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/dulate-mini-postres\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2020\/09\/33050046-F0E9-4FA6-B4FB-A0413AABE8BF-1.jpg' alt='33050046-F0E9-4FA6-B4FB-A0413AABE8BF' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/dulate-mini-postres\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2020\/09\/B176FE6D-6881-4228-8A0D-94189062A8B0-1.jpg' alt='B176FE6D-6881-4228-8A0D-94189062A8B0' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/dulate-mini-postres\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2020\/09\/C9BDD077-AD13-4E56-90BC-A4212477AA4E-1.jpg' alt='C9BDD077-AD13-4E56-90BC-A4212477AA4E' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/dulate-mini-postres\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2020\/09\/D851A975-C13F-426E-AD1D-E583326BCEA9-1.jpg' alt='D851A975-C13F-426E-AD1D-E583326BCEA9' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/dulate-mini-postres\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2020\/09\/F2E9F607-2F42-4245-BACB-32BEE38CCA1F-1.jpg' alt='F2E9F607-2F42-4245-BACB-32BEE38CCA1F' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><\/div>\n\t\t\t\t\t<div class='directorist-swiper__navigation'>\n\t\t\t\t\t\t<div class='directorist-swiper__nav directorist-swiper__nav--prev directorist-swiper__nav--prev-listing'><i class=\"directorist-icon-mask\" aria-hidden=\"true\" style=\"--directorist-icon: url(https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/plugins\/directorist\/assets\/icons\/line-awesome\/svgs\/angle-left-solid.svg)\"><\/i><\/div>\n\t\t\t\t\t\t<div class='directorist-swiper__nav directorist-swiper__nav--next directorist-swiper__nav--next-listing'><i class=\"directorist-icon-mask\" aria-hidden=\"true\" style=\"--directorist-icon: url(https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/plugins\/directorist\/assets\/icons\/line-awesome\/svgs\/angle-right-solid.svg)\"><\/i><\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class='directorist-swiper__pagination directorist-swiper__pagination--listing'><\/div>\n\t\t\t\t<\/div><\/div><\/div>\n        <div class=\"directorist-thumb-top-left\"><\/div>\n        <div class=\"directorist-thumb-top-right\"><\/div>\n        <div class=\"directorist-thumb-bottom-left\"><\/div>\n        <div class=\"directorist-thumb-bottom-right\"><\/div>\n\n    <\/div>\n\n    <div class=\"directorist-listing-single__content\">\n        <section class=\"directorist-listing-single__info\">\n\n            \n            <header class=\"directorist-listing-single__info__top\">\n                \n<h2 class=\"directorist-listing-title\"><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/dulate-mini-postres\/\">Dulate mini postres<\/a><\/h2>\n\n            <\/header>\n\n            \n            <ul class=\"directorist-listing-single__info__list\">\n                \n<li class=\"directorist-listing-card-phone\">\n    <i class=\"directorist-icon-mask\" aria-hidden=\"true\" style=\"--directorist-icon: url(https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/plugins\/directorist\/assets\/icons\/line-awesome\/svgs\/phone-solid.svg)\"><\/i>    <a href=\"tel:2294025025\">2294025025<\/a>\n<\/li>\n<li class=\"directorist-listing-card-website\">\n    <i class=\"directorist-icon-mask\" aria-hidden=\"true\" style=\"--directorist-icon: url(https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/plugins\/directorist\/assets\/icons\/line-awesome\/svgs\/globe-solid.svg)\"><\/i>        <a target=\"_blank\" rel=\"noopener\" href=\"http:\/\/www.dulate.mx\/\">\n        http:\/\/www.dulate.mx\/    <\/a>\n<\/li>            <\/ul>\n\n            \n                            \n<p class=\"directorist-listing-single__info__excerpt\">\n    Tartaletas a base de diferentes rellenos<a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/dulate-mini-postres\/\"> M\u00e1s info<\/a><\/p>\n            \n                    <\/section>\n\n        <footer class=\"directorist-listing-single__meta\">\n            <div class=\"directorist-listing-single__meta__left\">\n<div class=\"directorist-listing-category\">\n            <a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/categoria\/reposteria\/?directory_type=general\">Reposter\u00eda<\/a>\n                    <div class=\"directorist-listing-category__popup\">\n                <span class=\"directorist-listing-category__extran-count\">+1<\/span>\n                <div class=\"directorist-listing-category__popup__content\">\n                    \n                        <a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/categoria\/todas-las-categorias\/?directory_type=general\"> Todas las categor\u00edas<\/a>\n\n                                        <\/div>\n\n            <\/div>\n            <\/div>\n<\/div>\n            <div class=\"directorist-listing-single__meta__right\"><\/div>\n        <\/footer>\n    <\/div>\n\n<\/article>            <\/div>\n                        <div class=\"directorist-col-3\">\n                \n<article class=\"directorist-listing-single directorist-listing-single--bg directorist-listing-card directorist-listing-has-thumb directorist-single-line\">\n\n    <div class=\"directorist-listing-single__thumb\">\n\n        <div class='directorist-thumnail-card directorist-card-contain' style='height: 260px;background-color: white'><div class='directorist-thumnail-card-front-wrap'><div class='directorist-swiper directorist-swiper-listing' data-sw-items='1' data-sw-margin='2' data-sw-loop='true' data-sw-perslide='1' data-sw-speed='500' data-sw-autoplay='false' data-sw-responsive='{}'>\n\t\t\t\t\t<div class='swiper-wrapper'><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/estuches-y-cajas-de-pvc-moukarzel\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2021\/05\/LOGO-ESTUCHES-NUEVO.jpg' alt='LOGO-ESTUCHES-NUEVO' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/estuches-y-cajas-de-pvc-moukarzel\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2021\/05\/Estuches-Plasticos-trebol.jpg' alt='Estuches-Plasticos-trebol' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/estuches-y-cajas-de-pvc-moukarzel\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2021\/05\/Estuches-Plasticos-palomera-ch-p.jpg' alt='Estuches-Plasticos-palomera-ch-p' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/estuches-y-cajas-de-pvc-moukarzel\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2021\/05\/Estuches-Plasticos-m-Cubos.jpg' alt='Estuches-Plasticos-m-Cubos' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/estuches-y-cajas-de-pvc-moukarzel\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2021\/05\/Estuches-Plasticos-Lonchera-REC-p.jpg' alt='Estuches-Plasticos-Lonchera-REC-p' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/estuches-y-cajas-de-pvc-moukarzel\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2021\/05\/Estuches-Plasticos-China-gp.jpg' alt='Estuches-Plasticos-China-gp' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/estuches-y-cajas-de-pvc-moukarzel\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2021\/05\/Estuches-Plasticos-China-chp.jpg' alt='Estuches-Plasticos-China-chp' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><\/div>\n\t\t\t\t\t<div class='directorist-swiper__navigation'>\n\t\t\t\t\t\t<div class='directorist-swiper__nav directorist-swiper__nav--prev directorist-swiper__nav--prev-listing'><i class=\"directorist-icon-mask\" aria-hidden=\"true\" style=\"--directorist-icon: url(https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/plugins\/directorist\/assets\/icons\/line-awesome\/svgs\/angle-left-solid.svg)\"><\/i><\/div>\n\t\t\t\t\t\t<div class='directorist-swiper__nav directorist-swiper__nav--next directorist-swiper__nav--next-listing'><i class=\"directorist-icon-mask\" aria-hidden=\"true\" style=\"--directorist-icon: url(https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/plugins\/directorist\/assets\/icons\/line-awesome\/svgs\/angle-right-solid.svg)\"><\/i><\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class='directorist-swiper__pagination directorist-swiper__pagination--listing'><\/div>\n\t\t\t\t<\/div><\/div><\/div>\n        <div class=\"directorist-thumb-top-left\"><\/div>\n        <div class=\"directorist-thumb-top-right\"><\/div>\n        <div class=\"directorist-thumb-bottom-left\"><\/div>\n        <div class=\"directorist-thumb-bottom-right\"><\/div>\n\n    <\/div>\n\n    <div class=\"directorist-listing-single__content\">\n        <section class=\"directorist-listing-single__info\">\n\n            \n            <header class=\"directorist-listing-single__info__top\">\n                \n<h2 class=\"directorist-listing-title\"><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/estuches-y-cajas-de-pvc-moukarzel\/\">Estuches y  cajas de pvc Moukarzel<\/a><\/h2>\n\n            <\/header>\n\n            \n            <ul class=\"directorist-listing-single__info__list\">\n                \n<li class=\"directorist-listing-card-phone\">\n    <i class=\"directorist-icon-mask\" aria-hidden=\"true\" style=\"--directorist-icon: url(https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/plugins\/directorist\/assets\/icons\/line-awesome\/svgs\/phone-solid.svg)\"><\/i>    <a href=\"tel:5512930509\">5512930509<\/a>\n<\/li>\n<li class=\"directorist-listing-card-website\">\n    <i class=\"directorist-icon-mask\" aria-hidden=\"true\" style=\"--directorist-icon: url(https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/plugins\/directorist\/assets\/icons\/line-awesome\/svgs\/globe-solid.svg)\"><\/i>        <a target=\"_blank\" rel=\"noopener\" href=\"http:\/\/www.estuchesplasticos.mx\">\n        http:\/\/www.estuchesplasticos.mx    <\/a>\n<\/li>            <\/ul>\n\n            \n                            \n<p class=\"directorist-listing-single__info__excerpt\">\n    Ofrecemos la elaboraci\u00f3n de estuches en PVC&hellip;<a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/estuches-y-cajas-de-pvc-moukarzel\/\"> M\u00e1s info<\/a><\/p>\n            \n                    <\/section>\n\n        <footer class=\"directorist-listing-single__meta\">\n            <div class=\"directorist-listing-single__meta__left\">\n<div class=\"directorist-listing-category\">\n            <a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/categoria\/manualidades-en-general\/?directory_type=general\">Manualidades en general<\/a>\n                    <div class=\"directorist-listing-category__popup\">\n                <span class=\"directorist-listing-category__extran-count\">+2<\/span>\n                <div class=\"directorist-listing-category__popup__content\">\n                    \n                        <a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/categoria\/reposteria\/?directory_type=general\"> Reposter\u00eda<\/a>\n\n                        \n                        <a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/categoria\/todas-las-categorias\/?directory_type=general\"> Todas las categor\u00edas<\/a>\n\n                                        <\/div>\n\n            <\/div>\n            <\/div>\n<\/div>\n            <div class=\"directorist-listing-single__meta__right\"><\/div>\n        <\/footer>\n    <\/div>\n\n<\/article>            <\/div>\n                        <div class=\"directorist-col-3\">\n                \n<article class=\"directorist-listing-single directorist-listing-single--bg directorist-listing-card directorist-listing-has-thumb directorist-single-line\">\n\n    <div class=\"directorist-listing-single__thumb\">\n\n        <div class='directorist-thumnail-card directorist-card-contain' style='height: 260px;background-color: white'><div class='directorist-thumnail-card-front-wrap'><div class='directorist-swiper directorist-swiper-listing' data-sw-items='1' data-sw-margin='2' data-sw-loop='true' data-sw-perslide='1' data-sw-speed='500' data-sw-autoplay='false' data-sw-responsive='{}'>\n\t\t\t\t\t<div class='swiper-wrapper'><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/impulsora-de-pinceles-de-arte-sa-de-cv\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2021\/04\/LogoRexOriginal_.jpg' alt='LogoRexOriginal_' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/impulsora-de-pinceles-de-arte-sa-de-cv\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2022\/08\/1-3-1_.jpg' alt='1-3-1_' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/impulsora-de-pinceles-de-arte-sa-de-cv\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2022\/08\/2-2-1_.jpg' alt='2-2-1_' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/impulsora-de-pinceles-de-arte-sa-de-cv\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2022\/08\/3-2-1_.jpg' alt='3-2-1_' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/impulsora-de-pinceles-de-arte-sa-de-cv\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2022\/08\/9-4_.jpg' alt='9-4_' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/impulsora-de-pinceles-de-arte-sa-de-cv\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2022\/08\/5-3.jpg' alt='5-3' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/impulsora-de-pinceles-de-arte-sa-de-cv\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2022\/08\/4-5.jpg' alt='4-5' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><\/div>\n\t\t\t\t\t<div class='directorist-swiper__navigation'>\n\t\t\t\t\t\t<div class='directorist-swiper__nav directorist-swiper__nav--prev directorist-swiper__nav--prev-listing'><i class=\"directorist-icon-mask\" aria-hidden=\"true\" style=\"--directorist-icon: url(https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/plugins\/directorist\/assets\/icons\/line-awesome\/svgs\/angle-left-solid.svg)\"><\/i><\/div>\n\t\t\t\t\t\t<div class='directorist-swiper__nav directorist-swiper__nav--next directorist-swiper__nav--next-listing'><i class=\"directorist-icon-mask\" aria-hidden=\"true\" style=\"--directorist-icon: url(https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/plugins\/directorist\/assets\/icons\/line-awesome\/svgs\/angle-right-solid.svg)\"><\/i><\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class='directorist-swiper__pagination directorist-swiper__pagination--listing'><\/div>\n\t\t\t\t<\/div><\/div><\/div>\n        <div class=\"directorist-thumb-top-left\"><\/div>\n        <div class=\"directorist-thumb-top-right\"><\/div>\n        <div class=\"directorist-thumb-bottom-left\"><\/div>\n        <div class=\"directorist-thumb-bottom-right\"><\/div>\n\n    <\/div>\n\n    <div class=\"directorist-listing-single__content\">\n        <section class=\"directorist-listing-single__info\">\n\n            \n            <header class=\"directorist-listing-single__info__top\">\n                \n<h2 class=\"directorist-listing-title\"><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/impulsora-de-pinceles-de-arte-sa-de-cv\/\">Impulsora de Pinceles de Arte SA de CV<\/a><\/h2>\n\n            <\/header>\n\n            \n            <ul class=\"directorist-listing-single__info__list\">\n                \n<li class=\"directorist-listing-card-phone\">\n    <i class=\"directorist-icon-mask\" aria-hidden=\"true\" style=\"--directorist-icon: url(https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/plugins\/directorist\/assets\/icons\/line-awesome\/svgs\/phone-solid.svg)\"><\/i>    <a href=\"tel:55584029205558402930555863468555586305545558451947\">5558402920, 5558402930, 5558634685, 5558630554 Y 5558451947<\/a>\n<\/li>\n<li class=\"directorist-listing-card-website\">\n    <i class=\"directorist-icon-mask\" aria-hidden=\"true\" style=\"--directorist-icon: url(https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/plugins\/directorist\/assets\/icons\/line-awesome\/svgs\/globe-solid.svg)\"><\/i>        <a target=\"_blank\" rel=\"noopener\" href=\"http:\/\/www.pincelesrex.com.mx\/\">\n        http:\/\/www.pincelesrex.com.mx\/    <\/a>\n<\/li>            <\/ul>\n\n            \n                            \n<p class=\"directorist-listing-single__info__excerpt\">\n    PINCELES REX FABRICANTE MEXICANO 100%<a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/impulsora-de-pinceles-de-arte-sa-de-cv\/\"> M\u00e1s info<\/a><\/p>\n            \n                    <\/section>\n\n        <footer class=\"directorist-listing-single__meta\">\n            <div class=\"directorist-listing-single__meta__left\">\n<div class=\"directorist-listing-category\">\n            <a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/categoria\/arte-pintura\/?directory_type=general\">Arte y pintura<\/a>\n                    <div class=\"directorist-listing-category__popup\">\n                <span class=\"directorist-listing-category__extran-count\">+6<\/span>\n                <div class=\"directorist-listing-category__popup__content\">\n                    \n                        <a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/categoria\/decoracion\/?directory_type=general\"> Decoraci\u00f3n<\/a>\n\n                        \n                        <a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/categoria\/madera\/?directory_type=general\"> Madera<\/a>\n\n                        \n                        <a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/categoria\/manualidades-en-general\/?directory_type=general\"> Manualidades en general<\/a>\n\n                        \n                        <a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/categoria\/pasta-flexible\/?directory_type=general\"> Pasta Flexible<\/a>\n\n                        \n                        <a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/categoria\/reposteria\/?directory_type=general\"> Reposter\u00eda<\/a>\n\n                        \n                        <a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/categoria\/todas-las-categorias\/?directory_type=general\"> Todas las categor\u00edas<\/a>\n\n                                        <\/div>\n\n            <\/div>\n            <\/div>\n<\/div>\n            <div class=\"directorist-listing-single__meta__right\"><\/div>\n        <\/footer>\n    <\/div>\n\n<\/article>            <\/div>\n                        <div class=\"directorist-col-3\">\n                \n<article class=\"directorist-listing-single directorist-listing-single--bg directorist-listing-card directorist-listing-has-thumb directorist-single-line\">\n\n    <div class=\"directorist-listing-single__thumb\">\n\n        <div class='directorist-thumnail-card directorist-card-contain' style='height: 260px;background-color: white'><div class='directorist-thumnail-card-front-wrap'><div class='directorist-swiper directorist-swiper-listing' data-sw-items='1' data-sw-margin='2' data-sw-loop='true' data-sw-perslide='1' data-sw-speed='500' data-sw-autoplay='false' data-sw-responsive='{}'>\n\t\t\t\t\t<div class='swiper-wrapper'><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/manualidadesclick-directorio-nacional\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2021\/04\/Logomanualidadesok_.jpg' alt='Logomanualidadesok_' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/manualidadesclick-directorio-nacional\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2021\/04\/foto1_.jpg' alt='foto1_' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/manualidadesclick-directorio-nacional\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2021\/04\/foto2_.jpg' alt='foto2_' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/manualidadesclick-directorio-nacional\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2021\/04\/foto3_.jpg' alt='foto3_' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/manualidadesclick-directorio-nacional\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2021\/04\/foto4_.jpg' alt='foto4_' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/manualidadesclick-directorio-nacional\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2021\/04\/foto5_.jpg' alt='foto5_' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><div class='swiper-slide'><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/manualidadesclick-directorio-nacional\/\"><figure><img src='https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/uploads\/2021\/04\/foto6_.jpg' alt='foto6_' class='directorist-thumnail-card-front-img' \/><\/figure><\/a><\/div><\/div>\n\t\t\t\t\t<div class='directorist-swiper__navigation'>\n\t\t\t\t\t\t<div class='directorist-swiper__nav directorist-swiper__nav--prev directorist-swiper__nav--prev-listing'><i class=\"directorist-icon-mask\" aria-hidden=\"true\" style=\"--directorist-icon: url(https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/plugins\/directorist\/assets\/icons\/line-awesome\/svgs\/angle-left-solid.svg)\"><\/i><\/div>\n\t\t\t\t\t\t<div class='directorist-swiper__nav directorist-swiper__nav--next directorist-swiper__nav--next-listing'><i class=\"directorist-icon-mask\" aria-hidden=\"true\" style=\"--directorist-icon: url(https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/plugins\/directorist\/assets\/icons\/line-awesome\/svgs\/angle-right-solid.svg)\"><\/i><\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class='directorist-swiper__pagination directorist-swiper__pagination--listing'><\/div>\n\t\t\t\t<\/div><\/div><\/div>\n        <div class=\"directorist-thumb-top-left\"><\/div>\n        <div class=\"directorist-thumb-top-right\"><\/div>\n        <div class=\"directorist-thumb-bottom-left\"><\/div>\n        <div class=\"directorist-thumb-bottom-right\"><\/div>\n\n    <\/div>\n\n    <div class=\"directorist-listing-single__content\">\n        <section class=\"directorist-listing-single__info\">\n\n            \n            <header class=\"directorist-listing-single__info__top\">\n                \n<h2 class=\"directorist-listing-title\"><a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/manualidadesclick-directorio-nacional\/\">Manualidadesclick Directorio Nacional<\/a><\/h2>\n\n            <\/header>\n\n            \n            <ul class=\"directorist-listing-single__info__list\">\n                \n<li class=\"directorist-listing-card-phone\">\n    <i class=\"directorist-icon-mask\" aria-hidden=\"true\" style=\"--directorist-icon: url(https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/plugins\/directorist\/assets\/icons\/line-awesome\/svgs\/phone-solid.svg)\"><\/i>    <a href=\"tel:5527131596\">552713-1596<\/a>\n<\/li>\n<li class=\"directorist-listing-card-website\">\n    <i class=\"directorist-icon-mask\" aria-hidden=\"true\" style=\"--directorist-icon: url(https:\/\/www.expomanualidades.info\/negocios-247\/wp-content\/plugins\/directorist\/assets\/icons\/line-awesome\/svgs\/globe-solid.svg)\"><\/i>        <a target=\"_blank\" rel=\"noopener\" href=\"http:\/\/www.manualidadesclick.com.mx\/\">\n        http:\/\/www.manualidadesclick.com.mx\/    <\/a>\n<\/li>            <\/ul>\n\n            \n                            \n<p class=\"directorist-listing-single__info__excerpt\">\n    Directorio y Revistas de manualidades, materiales, cortadores&hellip;<a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/Expositores\/manualidadesclick-directorio-nacional\/\"> M\u00e1s info<\/a><\/p>\n            \n                    <\/section>\n\n        <footer class=\"directorist-listing-single__meta\">\n            <div class=\"directorist-listing-single__meta__left\">\n<div class=\"directorist-listing-category\">\n            <a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/categoria\/libros\/?directory_type=general\">Libros<\/a>\n                    <div class=\"directorist-listing-category__popup\">\n                <span class=\"directorist-listing-category__extran-count\">+4<\/span>\n                <div class=\"directorist-listing-category__popup__content\">\n                    \n                        <a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/categoria\/pasta-flexible\/?directory_type=general\"> Pasta Flexible<\/a>\n\n                        \n                        <a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/categoria\/reposteria\/?directory_type=general\"> Reposter\u00eda<\/a>\n\n                        \n                        <a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/categoria\/tarjeteria-filigrana\/?directory_type=general\"> Tarjeter\u00eda\/ filigrana<\/a>\n\n                        \n                        <a href=\"https:\/\/www.expomanualidades.info\/negocios-247\/categoria\/todas-las-categorias\/?directory_type=general\"> Todas las categor\u00edas<\/a>\n\n                                        <\/div>\n\n            <\/div>\n            <\/div>\n<\/div>\n            <div class=\"directorist-listing-single__meta__right\"><\/div>\n        <\/footer>\n    <\/div>\n\n<\/article>            <\/div>\n            \n            <\/div>\n\n            \n            \n            <\/div>\n<\/div>    <\/div>\n\n<\/div>[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text css=&#8221;.vc_custom_1601566587487{margin-top: -30px !important;}&#8221;][\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"templates\/full-width.php","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"class_list":["post-2287","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.expomanualidades.info\/negocios-247\/wp-json\/wp\/v2\/pages\/2287","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.expomanualidades.info\/negocios-247\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.expomanualidades.info\/negocios-247\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.expomanualidades.info\/negocios-247\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.expomanualidades.info\/negocios-247\/wp-json\/wp\/v2\/comments?post=2287"}],"version-history":[{"count":3,"href":"https:\/\/www.expomanualidades.info\/negocios-247\/wp-json\/wp\/v2\/pages\/2287\/revisions"}],"predecessor-version":[{"id":2294,"href":"https:\/\/www.expomanualidades.info\/negocios-247\/wp-json\/wp\/v2\/pages\/2287\/revisions\/2294"}],"wp:attachment":[{"href":"https:\/\/www.expomanualidades.info\/negocios-247\/wp-json\/wp\/v2\/media?parent=2287"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}